{"id":59031,"date":"2023-12-14T12:17:25","date_gmt":"2023-12-14T11:17:26","guid":{"rendered":"https:\/\/benvolio.bio\/?post_type=product&#038;p=59031"},"modified":"2025-03-17T00:00:20","modified_gmt":"2025-03-16T23:00:20","slug":"cafe-dersut-wizebite-cafe-plus-grain-1kg","status":"publish","type":"product","link":"https:\/\/benvolio.bio\/fr\/boutique\/all-fr\/cafe-dersut-wizebite-cafe-plus-grain-1kg\/","title":{"rendered":"Dersut Caf\u00e9 en Grains Plus Gold Harmonieux et Doux 1kg"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u2615 Caff\u00e8 Plus Oro : un m\u00e9lange exclusif d&rsquo;Arabica de haute qualit\u00e9, au go\u00fbt doux et intense avec des notes de cacao et de noisette. M\u00e9daill\u00e9 \ud83c\udfc5, symbole de l&rsquo;Espresso Italiano di Qualit\u00e0<\/p>\n","protected":false},"featured_media":60100,"template":"","meta":{"_acf_changed":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":""},"product_brand":[6011,6010],"product_cat":[3592,5973,5912],"product_tag":[5974],"class_list":["post-59031","product","type-product","status-publish","has-post-thumbnail","product_brand-dersut","product_brand-wizebite_choice","product_cat-all-fr","product_cat-cafe-dersut","product_cat-wizebitechoice-fr","product_tag-dersut-fr","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":{"descrizione":"<div class=\"flex-1 overflow-hidden\">\n<div class=\"react-scroll-to-bottom--css-vndsu-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-vndsu-1n7m0yu\">\n<div class=\"flex flex-col pb-9 text-sm\">\n<div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-53\">\n<div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\">\n<div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\">\n<div class=\"relative flex w-full flex-col lg:w-[calc(100%-115px)] agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"0e557cbf-79b7-424c-92c4-4bddb4c109e9\">\n<div class=\"markdown prose w-full break-words dark:prose-invert dark\">\n<ol>\n \t<li>\ud83c\udf10 <strong>S<\/strong>\u00e9lection d'<strong>Arabica d'\u00e9lite<\/strong>: Seuls les meilleurs grains d'Arabica sont s\u00e9lectionn\u00e9s pour Plus Oro, dans des r\u00e9gions r\u00e9put\u00e9es pour leur qualit\u00e9 sup\u00e9rieure. Cette s\u00e9lection minutieuse garantit un profil aromatique distinctif, caract\u00e9ris\u00e9 par un \u00e9quilibre impeccable entre douceur et intensit\u00e9, pour une exp\u00e9rience de d\u00e9gustation in\u00e9gal\u00e9e.<\/li>\n \t<li>\ud83c\udf6b <strong>Profils aromatiques riches<\/strong>: Le m\u00e9lange Plus Oro se caract\u00e9rise par sa saveur douce et intense, enrichie par des notes profondes de p\u00e2tisserie, de cacao et de noisette. Chaque gorg\u00e9e est un voyage \u00e0 travers des senteurs qui rappellent les d\u00e9lices d'une p\u00e2tisserie haut de gamme, pour aboutir \u00e0 une exp\u00e9rience olfactive et gustative m\u00e9morable.<\/li>\n \t<li>\ud83c\udfc5 <strong>Reconnu internationalement<\/strong>: Plus Oro a re\u00e7u la m\u00e9daille d'or \u00e0 l'International Coffee Tasting en 2014 et 2018, ce qui t\u00e9moigne de sa qualit\u00e9 exceptionnelle et de son attrait universel. Ces r\u00e9compenses soulignent l'engagement dans la recherche de la perfection et le succ\u00e8s dans la cr\u00e9ation d'un m\u00e9lange qui r\u00e9sonne avec les palais les plus fins.<\/li>\n \t<li>\u2615 <strong>Excellence certifi\u00e9e<\/strong>: Chaque grain de Plus Oro porte la promesse d'une authentique qualit\u00e9 d'espresso italien. Cette certification n'est pas seulement une reconnaissance du go\u00fbt sup\u00e9rieur, mais aussi de l'engagement \u00e0 offrir un caf\u00e9 qui r\u00e9pond \u00e0 des normes de production strictes, afin de garantir un espresso de premi\u00e8re qualit\u00e9 \u00e0 chaque fois.<\/li>\n \t<li>\ud83c\udfaf Un <strong>\u00e9quilibre parfait<\/strong>: La fine acidit\u00e9 et le corps moyen de Plus Oro cr\u00e9ent une harmonie parfaite dans la tasse, ce qui en fait le caf\u00e9 id\u00e9al \u00e0 tout moment de la journ\u00e9e. Cet \u00e9quilibre raffin\u00e9<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"w-full pt-2 md:pt-0 dark:border-white\/20 md:border-transparent md:dark:border-transparent md:w-[calc(100%-.5rem)]\"><form class=\"stretch mx-2 flex flex-row gap-3 last:mb-2 md:mx-4 md:last:mb-6 lg:mx-auto lg:max-w-2xl xl:max-w-3xl\">\n<div class=\"relative flex h-full flex-1 items-stretch md:flex-col\">\n<div class=\"flex w-full items-center\"><\/div>\n<\/div>\n<\/form><\/div>","informazioni_aggiuntive":"<table style=\"height: 125px;\" tabindex=\"-1\" width=\"326\" align=\"left\" data-is-focusable=\"true\">\n<tbody>\n<tr>\n<td><b>Code EAN<\/b><\/td>\n<td>8054042970014<\/td>\n<\/tr>\n<tr>\n<td><b>Lester<\/b><\/td>\n<td>1.000 g<\/td>\n<\/tr>\n<tr>\n<td><b>Dimensions<\/b><\/td>\n<td>22 x 14 x 6<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","conservazione":"Conserver le produit dans un endroit frais et sec.\nDUREE DE CONSERVATION : 12 mois.","ingredienti":"100% de grains de caf\u00e9 Arabica s\u00e9lectionn\u00e9s\nIncluant une s\u00e9lection de vari\u00e9t\u00e9s naturelles et lav\u00e9es pour un go\u00fbt doux et intense\nNotes de p\u00e2tisserie, de cacao et de noisette\nBelle acidit\u00e9 et corps moyen","tab_nutrizionale":"","titolo_faq_1":"Quelles sont les vari\u00e9t\u00e9s d'Arabica utilis\u00e9es dans Plus Oro ?","risposta_faq_1":"Les vari\u00e9t\u00e9s d'Arabica s\u00e9lectionn\u00e9es pour Plus Oro comprennent exclusivement des grains naturels et lav\u00e9s de la meilleure qualit\u00e9, choisis pour leur contribution unique au profil aromatique doux et intense du caf\u00e9.","titolo_faq_2":"Qu'est-ce qui diff\u00e9rencie Plus Oro des autres m\u00e9langes de caf\u00e9 ?","risposta_faq_2":"Plus Oro se distingue par sa composition de grains 100% Arabica de haute qualit\u00e9, doublement r\u00e9compens\u00e9e par la M\u00e9daille d'Or de la D\u00e9gustation Internationale de Caf\u00e9 et par ses notes distinctives de p\u00e2tisserie, de cacao et de noisette, ainsi que par une fine acidit\u00e9 et un corps moyennement cors\u00e9.","titolo_faq_3":"Plus Oro convient-il \u00e0 tous les types de machines \u00e0 caf\u00e9 ?","risposta_faq_3":"Plus Oro, en tant que m\u00e9lange de grains de caf\u00e9, est polyvalent et convient \u00e0 une large gamme de machines \u00e0 caf\u00e9, y compris les moulins \u00e0 espresso, les mokas et les machines \u00e0 caf\u00e9 automatiques, permettant aux amateurs de caf\u00e9 de profiter de sa qualit\u00e9 sup\u00e9rieure avec la m\u00e9thode de pr\u00e9paration qu'ils pr\u00e9f\u00e8rent.","titolo_faq_4":"Comment conserver Caff\u00e8 Plus Oro pour en pr\u00e9server la fra\u00eecheur ?","risposta_faq_4":"Pour pr\u00e9server la fra\u00eecheur et l'ar\u00f4me de Caff\u00e8 Plus Oro, il est recommand\u00e9 de le conserver dans un endroit frais et sec, \u00e0 l'abri des sources de chaleur et de la lumi\u00e8re directe. Il est pr\u00e9f\u00e9rable d'utiliser un r\u00e9cipient herm\u00e9tique pour conserver le plus longtemps possible les propri\u00e9t\u00e9s organoleptiques des haricots.","titolo_faq_5":"Plus Oro contient-il des allerg\u00e8nes ou convient-il \u00e0 des r\u00e9gimes sp\u00e9ciaux ?","risposta_faq_5":"Plus Oro est compos\u00e9 exclusivement de grains de caf\u00e9 100% Arabica et ne contient pas d'allerg\u00e8nes ajout\u00e9s. Il convient aux v\u00e9g\u00e9taliens, aux personnes souffrant d'intol\u00e9rances ou d'allergies alimentaires courantes et s'int\u00e8gre parfaitement \u00e0 presque tous les r\u00e9gimes, offrant un choix de boissons naturelles de haute qualit\u00e9 sans compromis sur le go\u00fbt ou la sant\u00e9."},"_links":{"self":[{"href":"https:\/\/benvolio.bio\/fr\/wp-json\/wp\/v2\/product\/59031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/benvolio.bio\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/benvolio.bio\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/benvolio.bio\/fr\/wp-json\/wp\/v2\/product\/59031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/benvolio.bio\/fr\/wp-json\/wp\/v2\/media\/60100"}],"wp:attachment":[{"href":"https:\/\/benvolio.bio\/fr\/wp-json\/wp\/v2\/media?parent=59031"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/benvolio.bio\/fr\/wp-json\/wp\/v2\/product_brand?post=59031"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/benvolio.bio\/fr\/wp-json\/wp\/v2\/product_cat?post=59031"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/benvolio.bio\/fr\/wp-json\/wp\/v2\/product_tag?post=59031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}