{"id":36612,"date":"2022-07-15T08:41:06","date_gmt":"2022-07-15T07:41:07","guid":{"rendered":"https:\/\/benvolio.bio\/?post_type=product&#038;p=36612"},"modified":"2022-09-12T10:03:38","modified_gmt":"2022-09-12T09:03:38","slug":"bio-protein-haselnuss-creme-200g","status":"publish","type":"product","link":"https:\/\/benvolio.bio\/de\/produkte\/all-de\/bio-protein-haselnuss-creme-200g\/","title":{"rendered":"Bio Protein Haselnuss Creme mit Kakao Geschmack 200g"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Der Benvolio 1938 <strong>Proteinaufstrich<\/strong> mit Haselnuss- und Kakaogeschmack enth\u00e4lt <strong>100 % Bio-Zutaten<\/strong> , hat einen hohen <strong>Proteingehalt<\/strong> , ist <strong>reich an Ballaststoffen<\/strong> und <strong>enth\u00e4lt kein Palm\u00f6l<\/strong> .<\/p>\n","protected":false},"featured_media":36625,"template":"","meta":{"_acf_changed":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":""},"product_brand":[2639],"product_cat":[1864,2781,1873],"product_tag":[3479],"class_list":["post-36612","product","type-product","status-publish","has-post-thumbnail","product_brand-benvolio-studio","product_cat-all-de","product_cat-benvolio-studio-de","product_cat-bio","product_tag-streichfahige-creme","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":{"descrizione":"Die Proteincreme mit Haselnuss- und Kakaogeschmack von Benvolio 1938 enth\u00e4lt <strong>100 % Bio<\/strong> -Zutaten.\r\n\r\nEs zeichnet sich durch einen <strong>hohen Proteingehalt von 25 % aus<\/strong> , ist <strong>reich an Ballaststoffen<\/strong> und <strong>enth\u00e4lt kein Palm\u00f6l<\/strong> .\r\n\r\nEs ist mit <strong>Erythrit<\/strong> , einem nat\u00fcrlichen S\u00fc\u00dfstoff, ges\u00fc\u00dft und <strong>enth\u00e4lt keinen Zuckerzusatz<\/strong> . Dies macht es zu einem hervorragenden Produkt f\u00fcr den <strong>Keto-Lebensstil<\/strong> .\r\n\r\nMit einer hellbraunen Farbe, die f\u00fcr Schokolade charakteristisch ist, und einem intensiven und s\u00fc\u00dfen Aroma. Bitterer und intensiver Nachgeschmack nach Kakao und gleichzeitig s\u00fc\u00df durch Milch.\r\n\r\nWeiche und cremige Textur, die sich hervorragend verteilen l\u00e4sst. Zum <strong>Fr\u00fchst\u00fcck oder als Snack<\/strong> w\u00e4hrend des Tages auf einer Scheibe Brot, einem Pfannkuchen oder sogar einem L\u00f6ffel. Auch <strong>f\u00fcr Snacks<\/strong> oder als <strong>Sportlernahrung<\/strong> geeignet.\r\n\r\nGlutenfrei und gentechnikfrei.","informazioni_aggiuntive":"<table style=\"height: 125px;\" tabindex=\"-1\" width=\"326\" align=\"left\" data-is-focusable=\"true\">\r\n<tbody>\r\n<tr>\r\n<td><b>EAN-Code<\/b><\/td>\r\n<td>8058333354019<\/td>\r\n<\/tr>\r\n<tr>\r\n<td><b>Gewicht<\/b><\/td>\r\n<td>200 gr<\/td>\r\n<\/tr>\r\n<tr>\r\n<td><b>Ma\u00dfe<\/b><\/td>\r\n<td>6 x 6,5 x 6,5<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>","conservazione":"Um die maximale Qualit\u00e4t zu erhalten und eine einfachere Verwendung des Produkts zu erm\u00f6glichen, haben wir uns f\u00fcr unsere Streichcreme f\u00fcr einen Kunststofftiegel entschieden.\r\nBei Temperaturen unter 30 \u00b0, fern von Licht- und W\u00e4rmequellen lagern.\r\nHALTBARKEIT: 24 Monate.","ingredienti":"Bio-Zutaten des Haselnuss Creme: Konzentriertes Molkeneiwei\u00df*, S\u00fc\u00dfungsmittel: Erythrit* (E968), Haselnusspaste* 13 %, Sonnenblumen\u00f6l*, Inulin*, Kokos\u00f6l*, Kakao*-Magerpulver 7 %, S\u00fc\u00dfmolkenpulver*, Emulgator: Sonnenblumenlecithin* (E322). * EU-\/Nicht-EU-Erzeugnisse aus \u00f6kologischem Landbau. Kann Spuren von EIER, SOJA, ANDEREN SCHALENFR\u00dcCHTEN (PISTAZIEN), ERDN\u00dcSSEN enthalten","tab_nutrizionale":"","titolo_faq_1":"Worauf kann ich die Haselnuss-Kakao-Creme streichen?","risposta_faq_1":"Der Bio-Aufstrich mit Haselnuss-Kakao-Geschmack kann auf Kuchen und Keksen, als Garnitur auf zarten Pfannkuchen, direkt auf dem L\u00f6ffel oder auf Brot zum Fr\u00fchst\u00fcck verwendet werden. ","titolo_faq_2":"Enth\u00e4lt Benvolio Streichcreme Zucker?","risposta_faq_2":"Es enth\u00e4lt keinen zugesetzten Zucker. Es wird dank eines nat\u00fcrlichen S\u00fc\u00dfungsmittels, Erythritol, ges\u00fc\u00dft, das mit Erfolg verwendet wird, da es keine Kalorien und einen ausgezeichneten Geschmack ohne Nachgeschmack hat.","titolo_faq_3":"Wo kann die Benvolio Streichcreme aufbewahrt werden?","risposta_faq_3":"Benvolio 1938 Bio Protein Haselnuss Creme mit Kakao Geschmack kann bei Raumtemperatur, k\u00fchl und trocken gelagert werden. ","titolo_faq_4":"Welche Konsistenz hat die Creme?","risposta_faq_4":"Der Benvolio 1938 Proteinaufstrich mit Haselnuss- und Kakaogeschmack hat die perfekte Dichte, die ihn weich, samtig und ideal zum Streichen macht.","titolo_faq_5":"Aus welchem Material besteht die Packung?","risposta_faq_5":"Um eine einfachere Verwendung des Produkts zu erm\u00f6glichen, haben wir f\u00fcr unsere Creme einen leichten, unzerbrechlichen und zu 100 % recycelbaren Kunststoffbeh\u00e4lter gew\u00e4hlt."},"_links":{"self":[{"href":"https:\/\/benvolio.bio\/de\/wp-json\/wp\/v2\/product\/36612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/benvolio.bio\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/benvolio.bio\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/benvolio.bio\/de\/wp-json\/wp\/v2\/product\/36612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/benvolio.bio\/de\/wp-json\/wp\/v2\/media\/36625"}],"wp:attachment":[{"href":"https:\/\/benvolio.bio\/de\/wp-json\/wp\/v2\/media?parent=36612"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/benvolio.bio\/de\/wp-json\/wp\/v2\/product_brand?post=36612"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/benvolio.bio\/de\/wp-json\/wp\/v2\/product_cat?post=36612"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/benvolio.bio\/de\/wp-json\/wp\/v2\/product_tag?post=36612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}